{"id":3812,"count":21,"description":"","link":"https:\/\/www.scandinavia.life\/de\/general-topics\/gesundheit\/","name":"Gesundheit","slug":"gesundheit","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.scandinavia.life\/de\/wp-json\/wp\/v2\/categories\/3812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scandinavia.life\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.scandinavia.life\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.scandinavia.life\/de\/wp-json\/wp\/v2\/posts?categories=3812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}