{"id":1971,"count":32,"description":"","link":"https:\/\/www.scandinavia.life\/no\/stikkord\/jobber\/","name":"jobber","slug":"jobber","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.scandinavia.life\/no\/wp-json\/wp\/v2\/tags\/1971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scandinavia.life\/no\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.scandinavia.life\/no\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.scandinavia.life\/no\/wp-json\/wp\/v2\/posts?tags=1971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}