{"id":25002,"count":9,"description":"","link":"https:\/\/www.scandinavia.life\/th\/general-topics\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%aa%e0%b8%b1%e0%b8%87%e0%b8%84%e0%b8%a1\/","name":"\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%aa%e0%b8%b1%e0%b8%87%e0%b8%84%e0%b8%a1","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.scandinavia.life\/th\/wp-json\/wp\/v2\/categories\/25002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scandinavia.life\/th\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.scandinavia.life\/th\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.scandinavia.life\/th\/wp-json\/wp\/v2\/posts?categories=25002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}