{"id":33298,"count":6,"description":"","link":"https:\/\/www.scandinavia.life\/tr\/genellikle\/vatandaslik\/","name":"Vatanda\u015fl\u0131k","slug":"vatandaslik","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.scandinavia.life\/tr\/wp-json\/wp\/v2\/tags\/33298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scandinavia.life\/tr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.scandinavia.life\/tr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.scandinavia.life\/tr\/wp-json\/wp\/v2\/posts?tags=33298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}